{"id":204,"count":1,"description":"","link":"https:\/\/papillionbusinesses.com\/blog\/tag\/free-coffee\/","name":"Free Coffee","slug":"free-coffee","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Free Coffee Archives - Papillion Businesses<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/papillionbusinesses.com\/blog\/tag\/free-coffee\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"en_US\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Free Coffee Archives - Papillion Businesses\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/papillionbusinesses.com\/blog\/tag\/free-coffee\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Papillion Businesses\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/papillionbusinesses.com\/blog\/wp-content\/uploads\/2026\/07\/cropped-papillionbusinessesdotcomdowntownpapillion600x450x180.png\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:site\" content=\"@papillionbus\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/papillionbusinesses.com\\\/blog\\\/tag\\\/free-coffee\\\/\",\"url\":\"https:\\\/\\\/papillionbusinesses.com\\\/blog\\\/tag\\\/free-coffee\\\/\",\"name\":\"Free Coffee Archives - Papillion Businesses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/papillionbusinesses.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/papillionbusinesses.com\\\/blog\\\/tag\\\/free-coffee\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/papillionbusinesses.com\\\/blog\\\/tag\\\/free-coffee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/papillionbusinesses.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Free Coffee\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/papillionbusinesses.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/papillionbusinesses.com\\\/blog\\\/\",\"name\":\"Papillion Businesses\",\"description\":\"Papillion: A Great Place to Live and Do Business!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/papillionbusinesses.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Free Coffee Archives - Papillion Businesses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/papillionbusinesses.com\/blog\/tag\/free-coffee\/","og_locale":"en_US","og_type":"article","og_title":"Free Coffee Archives - Papillion Businesses","og_url":"https:\/\/papillionbusinesses.com\/blog\/tag\/free-coffee\/","og_site_name":"Papillion Businesses","og_image":[{"width":512,"height":512,"url":"https:\/\/papillionbusinesses.com\/blog\/wp-content\/uploads\/2026\/07\/cropped-papillionbusinessesdotcomdowntownpapillion600x450x180.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@papillionbus","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/papillionbusinesses.com\/blog\/tag\/free-coffee\/","url":"https:\/\/papillionbusinesses.com\/blog\/tag\/free-coffee\/","name":"Free Coffee Archives - Papillion Businesses","isPartOf":{"@id":"https:\/\/papillionbusinesses.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/papillionbusinesses.com\/blog\/tag\/free-coffee\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/papillionbusinesses.com\/blog\/tag\/free-coffee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/papillionbusinesses.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Free Coffee"}]},{"@type":"WebSite","@id":"https:\/\/papillionbusinesses.com\/blog\/#website","url":"https:\/\/papillionbusinesses.com\/blog\/","name":"Papillion Businesses","description":"Papillion: A Great Place to Live and Do Business!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/papillionbusinesses.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/papillionbusinesses.com\/blog\/wp-json\/wp\/v2\/tags\/204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/papillionbusinesses.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/papillionbusinesses.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/papillionbusinesses.com\/blog\/wp-json\/wp\/v2\/posts?tags=204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}